{"id":54811,"date":"2026-05-25T14:00:07","date_gmt":"2026-05-25T18:00:07","guid":{"rendered":"https:\/\/esportems.com.br\/site\/?p=54811"},"modified":"2026-05-24T19:25:49","modified_gmt":"2026-05-24T23:25:49","slug":"andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao","status":"publish","type":"post","link":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/","title":{"rendered":"Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o"},"content":{"rendered":"<p>A Federa\u00e7\u00e3o de Futebol de Mato Grosso do Sul (FFMS) trabalha com o cronograma para iniciar, nas pr\u00f3ximas semanas, a troca completa do gramado do&nbsp;Est\u00e1dio Pedro Pedrossian, o Moren\u00e3o, em Campo Grande.<\/p>\n<p>O presidente da entidade, Estev\u00e3o Petrall\u00e1s, esteve na \u00faltima semana no Rio de Janeiro (RJ), onde se reuniu com o presidente da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), Samir Xaud, e entregou documentos com o projeto reformulado para instala\u00e7\u00e3o do novo gramado, implanta\u00e7\u00e3o do sistema de irriga\u00e7\u00e3o e outras melhorias estruturais.<\/p>\n<p>De acordo com Petrall\u00e1s, o&nbsp;compromisso para a substitui\u00e7\u00e3o completa do gramado foi reafirmado pela CBF. A interven\u00e7\u00e3o prev\u00ea a retirada total da estrutura atual e a implanta\u00e7\u00e3o de um novo campo, j\u00e1 equipado com sistema moderno de irriga\u00e7\u00e3o.<\/p>\n<p>Para falar sobre esse e outros assuntos relacionados a atual situa\u00e7\u00e3o do est\u00e1dio Moren\u00e3o, o novo administrador do est\u00e1dio, Andr\u00e9 Chita, vai nesta quinta-feira (28),&nbsp; no Podcast <span style=\"color: #ff0000;\"><strong>EsporteMS em Debate<\/strong><\/span>, a partir das 19h30, ao vivo, no canal do <a href=\"http:\/\/youtube.com\/esportems\">youtube.com\/esportems<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Federa\u00e7\u00e3o de Futebol de Mato Grosso do Sul (FFMS) trabalha com o cronograma para iniciar, nas pr\u00f3ximas semanas, a troca completa do gramado do&nbsp;Est\u00e1dio Pedro Pedrossian, o Moren\u00e3o, em Campo Grande. O presidente da entidade, Estev\u00e3o Petrall\u00e1s, esteve na \u00faltima semana no Rio de Janeiro (RJ), onde se reuniu com o presidente da Confedera\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":53815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[448,2],"tags":[],"class_list":["post-54811","post","type-post","status-publish","format-standard","has-post-thumbnail","category-atitude","category-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o - EsporteMS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o - EsporteMS\" \/>\n<meta property=\"og:description\" content=\"A Federa\u00e7\u00e3o de Futebol de Mato Grosso do Sul (FFMS) trabalha com o cronograma para iniciar, nas pr\u00f3ximas semanas, a troca completa do gramado do&nbsp;Est\u00e1dio Pedro Pedrossian, o Moren\u00e3o, em Campo Grande. O presidente da entidade, Estev\u00e3o Petrall\u00e1s, esteve na \u00faltima semana no Rio de Janeiro (RJ), onde se reuniu com o presidente da Confedera\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/\" \/>\n<meta property=\"og:site_name\" content=\"EsporteMS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100050621362784\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-25T18:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/04\/1-andre-chita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"901\" \/>\n\t<meta property=\"og:image:height\" content=\"734\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udio Severo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioEsporteMS\" \/>\n<meta name=\"twitter:site\" content=\"@RadioEsporteMS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udio Severo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/\"},\"author\":{\"name\":\"Cl\u00e1udio Severo\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#\\\/schema\\\/person\\\/f451b65748a8ce82d3ca25707a512dda\"},\"headline\":\"Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o\",\"datePublished\":\"2026-05-25T18:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/\"},\"wordCount\":198,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1-andre-chita.png\",\"articleSection\":[\"ATITUDE\",\"Featured\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/\",\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/\",\"name\":\"Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o - EsporteMS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1-andre-chita.png\",\"datePublished\":\"2026-05-25T18:00:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1-andre-chita.png\",\"contentUrl\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1-andre-chita.png\",\"width\":901,\"height\":734,\"caption\":\"Professor esteve visitando o local com comitiva para ver as necessidades (foto-divulga\u00e7\u00e3o)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/\",\"name\":\"EsporteMS\",\"description\":\"O melhor conte\u00fado de esporte de MS\",\"publisher\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#organization\",\"name\":\"EsporteMS\",\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo_esportems_250px.png\",\"contentUrl\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo_esportems_250px.png\",\"width\":250,\"height\":250,\"caption\":\"EsporteMS\"},\"image\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100050621362784\",\"https:\\\/\\\/x.com\\\/RadioEsporteMS\",\"https:\\\/\\\/www.instagram.com\\\/esportems2\\\/\",\"https:\\\/\\\/wa.me\\\/5567999590868\",\"https:\\\/\\\/www.youtube.com\\\/esportems\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#\\\/schema\\\/person\\\/f451b65748a8ce82d3ca25707a512dda\",\"name\":\"Cl\u00e1udio Severo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e1udio Severo\"},\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/author\\\/severo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o - EsporteMS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/","og_locale":"pt_BR","og_type":"article","og_title":"Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o - EsporteMS","og_description":"A Federa\u00e7\u00e3o de Futebol de Mato Grosso do Sul (FFMS) trabalha com o cronograma para iniciar, nas pr\u00f3ximas semanas, a troca completa do gramado do&nbsp;Est\u00e1dio Pedro Pedrossian, o Moren\u00e3o, em Campo Grande. O presidente da entidade, Estev\u00e3o Petrall\u00e1s, esteve na \u00faltima semana no Rio de Janeiro (RJ), onde se reuniu com o presidente da Confedera\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/","og_site_name":"EsporteMS","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100050621362784","article_published_time":"2026-05-25T18:00:07+00:00","og_image":[{"width":901,"height":734,"url":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/04\/1-andre-chita.png","type":"image\/png"}],"author":"Cl\u00e1udio Severo","twitter_card":"summary_large_image","twitter_creator":"@RadioEsporteMS","twitter_site":"@RadioEsporteMS","twitter_misc":{"Escrito por":"Cl\u00e1udio Severo","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/#article","isPartOf":{"@id":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/"},"author":{"name":"Cl\u00e1udio Severo","@id":"https:\/\/esportems.com.br\/site\/#\/schema\/person\/f451b65748a8ce82d3ca25707a512dda"},"headline":"Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o","datePublished":"2026-05-25T18:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/"},"wordCount":198,"commentCount":0,"publisher":{"@id":"https:\/\/esportems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/#primaryimage"},"thumbnailUrl":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/04\/1-andre-chita.png","articleSection":["ATITUDE","Featured"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/","url":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/","name":"Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o - EsporteMS","isPartOf":{"@id":"https:\/\/esportems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/#primaryimage"},"image":{"@id":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/#primaryimage"},"thumbnailUrl":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/04\/1-andre-chita.png","datePublished":"2026-05-25T18:00:07+00:00","breadcrumb":{"@id":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/#primaryimage","url":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/04\/1-andre-chita.png","contentUrl":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/04\/1-andre-chita.png","width":901,"height":734,"caption":"Professor esteve visitando o local com comitiva para ver as necessidades (foto-divulga\u00e7\u00e3o)"},{"@type":"BreadcrumbList","@id":"https:\/\/esportems.com.br\/site\/andre-chita-e-o-convidado-na-quinta-pra-atualizar-situacao-do-morenao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/esportems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Andr\u00e9 Chita \u00e9 o convidado na quinta pra atualizar situa\u00e7\u00e3o do Moren\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/esportems.com.br\/site\/#website","url":"https:\/\/esportems.com.br\/site\/","name":"EsporteMS","description":"O melhor conte\u00fado de esporte de MS","publisher":{"@id":"https:\/\/esportems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esportems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/esportems.com.br\/site\/#organization","name":"EsporteMS","url":"https:\/\/esportems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/esportems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2022\/12\/logo_esportems_250px.png","contentUrl":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2022\/12\/logo_esportems_250px.png","width":250,"height":250,"caption":"EsporteMS"},"image":{"@id":"https:\/\/esportems.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100050621362784","https:\/\/x.com\/RadioEsporteMS","https:\/\/www.instagram.com\/esportems2\/","https:\/\/wa.me\/5567999590868","https:\/\/www.youtube.com\/esportems\/"]},{"@type":"Person","@id":"https:\/\/esportems.com.br\/site\/#\/schema\/person\/f451b65748a8ce82d3ca25707a512dda","name":"Cl\u00e1udio Severo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g","caption":"Cl\u00e1udio Severo"},"url":"https:\/\/esportems.com.br\/site\/author\/severo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/posts\/54811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/comments?post=54811"}],"version-history":[{"count":1,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/posts\/54811\/revisions"}],"predecessor-version":[{"id":54812,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/posts\/54811\/revisions\/54812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/media\/53815"}],"wp:attachment":[{"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/media?parent=54811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/categories?post=54811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/tags?post=54811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}