{"id":54846,"date":"2026-05-28T11:24:37","date_gmt":"2026-05-28T15:24:37","guid":{"rendered":"https:\/\/esportems.com.br\/site\/?p=54846"},"modified":"2026-05-28T11:24:37","modified_gmt":"2026-05-28T15:24:37","slug":"cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil","status":"publish","type":"post","link":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/","title":{"rendered":"Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil"},"content":{"rendered":"<p data-start=\"0\" data-end=\"318\">A Funda\u00e7\u00e3o Municipal de Esportes (Funesp) deve anunciar a montagem da \u201cCidade da Copa\u201d para reunir torcedores durante os jogos da Sele\u00e7\u00e3o Brasileira. A informa\u00e7\u00e3o foi confirmada pelo diretor-presidente da funda\u00e7\u00e3o, <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Maicon Mommad<\/span><\/span>, em entrevista ao Portal EsporteMS.<\/p>\n<p data-start=\"320\" data-end=\"581\">De acordo com o dirigente, o espa\u00e7o j\u00e1 tem local definido e ser\u00e1 instalado na Esta\u00e7\u00e3o Ferrovi\u00e1ria, em Campo Grande, prometendo reunir fam\u00edlias, amantes do futebol e a popula\u00e7\u00e3o em geral para acompanhar as partidas do Brasil em clima de festa e confraterniza\u00e7\u00e3o.<\/p>\n<p data-start=\"583\" data-end=\"821\">A expectativa \u00e9 que a estrutura conte com tel\u00f5es, pra\u00e7a de alimenta\u00e7\u00e3o, atra\u00e7\u00f5es culturais e espa\u00e7o de conviv\u00eancia para os torcedores. A proposta \u00e9 transformar o local em um grande ponto de encontro durante os jogos da Sele\u00e7\u00e3o Brasileira.<\/p>\n<p data-start=\"823\" data-end=\"981\">Segundo <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Maicon Mommad<\/span><\/span>, os detalhes oficiais da programa\u00e7\u00e3o e da estrutura devem ser divulgados em breve pela prefeitura e pela Funesp.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Funda\u00e7\u00e3o Municipal de Esportes (Funesp) deve anunciar a montagem da \u201cCidade da Copa\u201d para reunir torcedores durante os jogos da Sele\u00e7\u00e3o Brasileira. A informa\u00e7\u00e3o foi confirmada pelo diretor-presidente da funda\u00e7\u00e3o, Maicon Mommad, em entrevista ao Portal EsporteMS. De acordo com o dirigente, o espa\u00e7o j\u00e1 tem local definido e ser\u00e1 instalado na Esta\u00e7\u00e3o Ferrovi\u00e1ria, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"ngg_post_thumbnail":0,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[426,2],"tags":[],"class_list":["post-54846","post","type-post","status-publish","format-video","has-post-thumbnail","category-copa-do-mundo","category-featured","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil - EsporteMS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil - EsporteMS\" \/>\n<meta property=\"og:description\" content=\"A Funda\u00e7\u00e3o Municipal de Esportes (Funesp) deve anunciar a montagem da \u201cCidade da Copa\u201d para reunir torcedores durante os jogos da Sele\u00e7\u00e3o Brasileira. A informa\u00e7\u00e3o foi confirmada pelo diretor-presidente da funda\u00e7\u00e3o, Maicon Mommad, em entrevista ao Portal EsporteMS. De acordo com o dirigente, o espa\u00e7o j\u00e1 tem local definido e ser\u00e1 instalado na Esta\u00e7\u00e3o Ferrovi\u00e1ria, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"EsporteMS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100050621362784\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-28T15:24:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/05\/maxresdefault-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udio Severo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioEsporteMS\" \/>\n<meta name=\"twitter:site\" content=\"@RadioEsporteMS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udio Severo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/\"},\"author\":{\"name\":\"Cl\u00e1udio Severo\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#\\\/schema\\\/person\\\/f451b65748a8ce82d3ca25707a512dda\"},\"headline\":\"Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil\",\"datePublished\":\"2026-05-28T15:24:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/\"},\"wordCount\":171,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/maxresdefault-12.jpg\",\"articleSection\":[\"COPA DO MUNDO\",\"Featured\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/\",\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/\",\"name\":\"Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil - EsporteMS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/maxresdefault-12.jpg\",\"datePublished\":\"2026-05-28T15:24:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/maxresdefault-12.jpg\",\"contentUrl\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/maxresdefault-12.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/\",\"name\":\"EsporteMS\",\"description\":\"O melhor conte\u00fado de esporte de MS\",\"publisher\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#organization\",\"name\":\"EsporteMS\",\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo_esportems_250px.png\",\"contentUrl\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo_esportems_250px.png\",\"width\":250,\"height\":250,\"caption\":\"EsporteMS\"},\"image\":{\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100050621362784\",\"https:\\\/\\\/x.com\\\/RadioEsporteMS\",\"https:\\\/\\\/www.instagram.com\\\/esportems2\\\/\",\"https:\\\/\\\/wa.me\\\/5567999590868\",\"https:\\\/\\\/www.youtube.com\\\/esportems\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/#\\\/schema\\\/person\\\/f451b65748a8ce82d3ca25707a512dda\",\"name\":\"Cl\u00e1udio Severo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e1udio Severo\"},\"url\":\"https:\\\/\\\/esportems.com.br\\\/site\\\/author\\\/severo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil - EsporteMS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil - EsporteMS","og_description":"A Funda\u00e7\u00e3o Municipal de Esportes (Funesp) deve anunciar a montagem da \u201cCidade da Copa\u201d para reunir torcedores durante os jogos da Sele\u00e7\u00e3o Brasileira. A informa\u00e7\u00e3o foi confirmada pelo diretor-presidente da funda\u00e7\u00e3o, Maicon Mommad, em entrevista ao Portal EsporteMS. De acordo com o dirigente, o espa\u00e7o j\u00e1 tem local definido e ser\u00e1 instalado na Esta\u00e7\u00e3o Ferrovi\u00e1ria, [&hellip;]","og_url":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/","og_site_name":"EsporteMS","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100050621362784","article_published_time":"2026-05-28T15:24:37+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/05\/maxresdefault-12.jpg","type":"image\/jpeg"}],"author":"Cl\u00e1udio Severo","twitter_card":"summary_large_image","twitter_creator":"@RadioEsporteMS","twitter_site":"@RadioEsporteMS","twitter_misc":{"Escrito por":"Cl\u00e1udio Severo","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/#article","isPartOf":{"@id":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/"},"author":{"name":"Cl\u00e1udio Severo","@id":"https:\/\/esportems.com.br\/site\/#\/schema\/person\/f451b65748a8ce82d3ca25707a512dda"},"headline":"Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil","datePublished":"2026-05-28T15:24:37+00:00","mainEntityOfPage":{"@id":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/"},"wordCount":171,"commentCount":0,"publisher":{"@id":"https:\/\/esportems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/05\/maxresdefault-12.jpg","articleSection":["COPA DO MUNDO","Featured"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/","url":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/","name":"Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil - EsporteMS","isPartOf":{"@id":"https:\/\/esportems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/#primaryimage"},"image":{"@id":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/05\/maxresdefault-12.jpg","datePublished":"2026-05-28T15:24:37+00:00","breadcrumb":{"@id":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/#primaryimage","url":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/05\/maxresdefault-12.jpg","contentUrl":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2026\/05\/maxresdefault-12.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/esportems.com.br\/site\/cidade-da-copa-sera-montada-na-estacao-ferroviaria-para-jogos-do-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/esportems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Cidade da Copa ser\u00e1 montada na Esta\u00e7\u00e3o Ferrovi\u00e1ria para jogos do Brasil"}]},{"@type":"WebSite","@id":"https:\/\/esportems.com.br\/site\/#website","url":"https:\/\/esportems.com.br\/site\/","name":"EsporteMS","description":"O melhor conte\u00fado de esporte de MS","publisher":{"@id":"https:\/\/esportems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esportems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/esportems.com.br\/site\/#organization","name":"EsporteMS","url":"https:\/\/esportems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/esportems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2022\/12\/logo_esportems_250px.png","contentUrl":"https:\/\/esportems.com.br\/site\/wp-content\/uploads\/2022\/12\/logo_esportems_250px.png","width":250,"height":250,"caption":"EsporteMS"},"image":{"@id":"https:\/\/esportems.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100050621362784","https:\/\/x.com\/RadioEsporteMS","https:\/\/www.instagram.com\/esportems2\/","https:\/\/wa.me\/5567999590868","https:\/\/www.youtube.com\/esportems\/"]},{"@type":"Person","@id":"https:\/\/esportems.com.br\/site\/#\/schema\/person\/f451b65748a8ce82d3ca25707a512dda","name":"Cl\u00e1udio Severo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94bcbd47e500b15b38519f79158a57abc1fa84f37255ad4b4be197699e1ff784?s=96&d=mm&r=g","caption":"Cl\u00e1udio Severo"},"url":"https:\/\/esportems.com.br\/site\/author\/severo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/posts\/54846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/comments?post=54846"}],"version-history":[{"count":1,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/posts\/54846\/revisions"}],"predecessor-version":[{"id":54848,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/posts\/54846\/revisions\/54848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/media\/54847"}],"wp:attachment":[{"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/media?parent=54846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/categories?post=54846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esportems.com.br\/site\/wp-json\/wp\/v2\/tags?post=54846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}